{"id":5844,"date":"2019-11-14T21:56:34","date_gmt":"2019-11-14T12:56:34","guid":{"rendered":"https:\/\/pokemon.gamepedia.jp\/ss\/items\/5844"},"modified":"2019-11-15T15:38:07","modified_gmt":"2019-11-15T06:38:07","slug":"item-305","status":"publish","type":"item","link":"https:\/\/pokemon.gamepedia.jp\/ss\/items\/5844","title":{"rendered":"\u3010\u30bd\u30fc\u30c9\u30b7\u30fc\u30eb\u30c9\u3011\u30d1\u30ef\u30fc\u30ea\u30b9\u30c8\u306e\u5165\u624b\u65b9\u6cd5\u3068\u52b9\u679c\u307e\u3068\u3081\u3010\u30dd\u30b1\u30e2\u30f3\u5263\u76fe\u3011"},"content":{"rendered":"<h2>\u57fa\u672c\u60c5\u5831<\/h2>\u7a2e\u985e\uff1a\n\n<a class=\"btn btn-terms-link  btn-terms btn-item_type btn-item_type-\u9053\u5177\" href=\"https:\/\/pokemon.gamepedia.jp\/ss\/items?item_type=%e9%81%93%e5%85%b7\">\u9053\u5177<\/a>\n<h3>\u52b9\u679c<\/h3><div class=\"text-l\">\u6301\u305f\u305b\u308b\u3068\u300c\u3059\u3070\u3084\u3055\u300d\u304c\u534a\u5206\u306b\u306a\u308b\u304c\u3001\u300c\u3053\u3046\u3052\u304d\u300d\u306e\u304d\u305d\u30dd\u30a4\u30f3\u30c8\u304c\u3088\u304f\u4e0a\u304c\u308b<\/div><div class=\"\" style=\"\"><\/div>\n\n<h2  class=\"headline\">\u5165\u624b\u65b9\u6cd5<\/h2>\n\n\n<h3  class=\"\">\u843d\u3061\u3066\u3044\u308b\u5834\u6240<\/h3>\n<p class=\"note-white\">\u306a\u3057<\/p>\n<h2>\u653b\u7565\u8a18\u4e8b<\/h2><ul class=\"media-list image-list \">\n  <div>\n<a href=\"https:\/\/pokemon.gamepedia.jp\/ss\/archives\/28332\">\n  <div class=\"media media-post\">\n    <div class=\"media-left\">\n      <img decoding=\"async\" class=\"media-object\" loading=\"lazy\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=150,h=150,fit=pad,f=webp\/media.gamepedia.jp\/pokemon.gamepedia.com\/wp-content\/uploads\/sites\/14\/2020\/04\/10154845\/2020y04m10d_154831606-480x480.jpg\" width=\"80\" height=\"80\" style=\"\"  \/>\n            <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n        \n        \u30de\u30c3\u30af\u30b9\u30ec\u30a4\u30c9\u30d0\u30c8\u30eb\u3067\u9ad8\u500b\u4f53\u5024\u30e1\u30bf\u30e2\u30f3\u30b2\u30c3\u30c8\u306e\u30c1\u30e3\u30f3\u30b9\uff01\u30d9\u30a4\u30d3\u30a3\u30dd\u30b1\u30e2\u30f3\u3082\u51fa\u73fe      <\/div>\n      <div class=\"media-meta\">\n\n        \n                <small class=\"media-meta-date\">\n          2020\u5e744\u670810\u65e5        <\/small>\n        \n                        <span class=\"label label-default label-post-type label-post-type-\u6295\u7a3f\">\u6295\u7a3f<\/span>\n                \n\n\n                                <span class=\"label label-default label-category label-category-\u30cb\u30e5\u30fc\u30b9\">\u30cb\u30e5\u30fc\u30b9<\/span>\n                                                        \n\n      <\/div>\n            <div class=\"media-desc\">\n        \r\n\r\n\u300e\u30dd\u30b1\u30c3\u30c8\u30e2\u30f3\u30b9\u30bf\u30fc \u30bd\u30fc\u30c9\u30fb\u30b7\u30fc\u30eb\u30c9(\u30dd\u30b1\u30e2\u30f3\u5263\u76fe)\u300f\u3067\u30014\u670810\u65e5\u304b\u308916\u65e5...      <\/div>\n      \n    <\/div>\n    <div class=\"clearfix\"><\/div>\n  <\/div>\n<\/a>\n\n<a href=\"https:\/\/pokemon.gamepedia.jp\/ss\/archives\/25445\">\n  <div class=\"media media-post\">\n    <div class=\"media-left\">\n      <img decoding=\"async\" class=\"media-object\" loading=\"lazy\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=150,h=150,fit=pad,f=webp\/images.gamepedia.jp\/common\/default_icon.png\" width=\"80\" height=\"80\" style=\"\"  \/>\n            <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n        \n        BP\u30b7\u30e7\u30c3\u30d7\u306e\u5834\u6240\u3068\u8cfc\u5165\u3067\u304d\u308b\u30a2\u30a4\u30c6\u30e0\u4e00\u89a7      <\/div>\n      <div class=\"media-meta\">\n\n        \n                <small class=\"media-meta-date\">\n          2019\u5e7412\u670816\u65e5        <\/small>\n        \n                        <span class=\"label label-default label-post-type label-post-type-\u6295\u7a3f\">\u6295\u7a3f<\/span>\n                \n\n\n                                <span class=\"label label-default label-category label-category-\u30d0\u30c8\u30eb\u30bf\u30ef\u30fc\">\u30d0\u30c8\u30eb\u30bf\u30ef\u30fc<\/span>\n                                                        \n\n      <\/div>\n            <div class=\"media-desc\">\n        \u300e\u30dd\u30b1\u30e2\u30f3\u30bb\u30f3\u30bf\u30fc \u30bd\u30fc\u30c9\u30fb\u30b7\u30fc\u30eb\u30c9(\u30dd\u30b1\u30e2\u30f3\u5263\u76fe)\u300f\u306eBP\u3092\u4f7f\u3063\u3066\u30a2\u30a4\u30c6\u30e0\u3092\u8cfc\u5165...      <\/div>\n      \n    <\/div>\n    <div class=\"clearfix\"><\/div>\n  <\/div>\n<\/a>\n\n<a href=\"https:\/\/pokemon.gamepedia.jp\/ss\/archives\/13511\">\n  <div class=\"media media-post\">\n    <div class=\"media-left\">\n      <img decoding=\"async\" class=\"media-object\" loading=\"lazy\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=150,h=150,fit=pad,f=webp\/media.gamepedia.jp\/pokemon.gamepedia.com\/wp-content\/uploads\/sites\/14\/2019\/11\/15092359\/04b4b6133aeba77ec408f52c55ddec03-480x270.png\" width=\"80\" height=\"80\" style=\"\"  \/>\n            <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n        \n        \u30d0\u30c8\u30eb\u30bf\u30ef\u30fc\u306e\u653b\u7565\u60c5\u5831\u307e\u3068\u3081\uff01\u89e3\u653e\u6761\u4ef6\u30fb\u5831\u916c\u30a2\u30a4\u30c6\u30e0\u4e00\u89a7\u306a\u3069      <\/div>\n      <div class=\"media-meta\">\n\n        \n                <small class=\"media-meta-date\">\n          2019\u5e7412\u670815\u65e5        <\/small>\n        \n                        <span class=\"label label-default label-post-type label-post-type-\u6295\u7a3f\">\u6295\u7a3f<\/span>\n                \n\n\n                                <span class=\"label label-default label-category label-category-\u30d0\u30c8\u30eb\u30bf\u30ef\u30fc\">\u30d0\u30c8\u30eb\u30bf\u30ef\u30fc<\/span>\n                                                        \n\n      <\/div>\n            <div class=\"media-desc\">\n        \r\n\r\n\u300e\u30dd\u30b1\u30c3\u30c8\u30e2\u30f3\u30b9\u30bf\u30fc \u30bd\u30fc\u30c9\u30fb\u30b7\u30fc\u30eb\u30c9(\u30dd\u30b1\u30e2\u30f3\u5263\u76fe)\u300f\u306b\u767b\u5834\u3059\u308b\u65bd\u8a2d\u306e1\u3064...      <\/div>\n      \n    <\/div>\n    <div class=\"clearfix\"><\/div>\n  <\/div>\n<\/a>\n\n    <\/div>\n    <div class=\"nav-more\" style=\"margin-top:10px;\">\n        <a class=\"btn btn-nav-more hide-me\" data-toggle=\"collapse\" href=\"#collapse-image-list-image-list-208924886\">\u3082\u3063\u3068\u898b\u308b<\/a>\n    <\/div>\n    <div id=\"collapse-image-list-image-list-208924886\" class=\"collapse\">\n<a href=\"https:\/\/pokemon.gamepedia.jp\/ss\/archives\/24966\">\n  <div class=\"media media-post\">\n    <div class=\"media-left\">\n      <img decoding=\"async\" class=\"media-object\" loading=\"lazy\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=150,h=150,fit=pad,f=webp\/media.gamepedia.jp\/pokemon.gamepedia.com\/wp-content\/uploads\/sites\/14\/2019\/12\/09142820\/df89818651a11982edc4aabf668e8ed2-480x270.png\" width=\"80\" height=\"80\" style=\"\"  \/>\n            <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n        \n        \u30dd\u30b1\u30b8\u30e7\u30d6\u3067\u52b9\u7387\u826f\u304f\u52aa\u529b\u5024\u3092\u7a3c\u3050\u65b9\u6cd5      <\/div>\n      <div class=\"media-meta\">\n\n        \n                <small class=\"media-meta-date\">\n          2019\u5e7412\u670810\u65e5        <\/small>\n        \n                        <span class=\"label label-default label-post-type label-post-type-\u6295\u7a3f\">\u6295\u7a3f<\/span>\n                \n\n\n                                <span class=\"label label-default label-category label-category-\u30dd\u30b1\u30b8\u30e7\u30d6\">\u30dd\u30b1\u30b8\u30e7\u30d6<\/span>\n                                                        \n\n      <\/div>\n            <div class=\"media-desc\">\n        \u300e\u30dd\u30b1\u30c3\u30c8\u30e2\u30f3\u30b9\u30bf\u30fc \u30bd\u30fc\u30c9\u30fb\u30b7\u30fc\u30eb\u30c9(\u30dd\u30b1\u30e2\u30f3\u5263\u76fe)\u300f\u3067\u30dd\u30b1\u30b8\u30e7\u30d6\u3092\u4f7f\u3063\u3066\u52aa\u529b...      <\/div>\n      \n    <\/div>\n    <div class=\"clearfix\"><\/div>\n  <\/div>\n<\/a>\n\n<a href=\"https:\/\/pokemon.gamepedia.jp\/ss\/archives\/16863\">\n  <div class=\"media media-post\">\n    <div class=\"media-left\">\n      <img decoding=\"async\" class=\"media-object\" loading=\"lazy\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=150,h=150,fit=pad,f=webp\/media.gamepedia.jp\/pokemon.gamepedia.com\/wp-content\/uploads\/sites\/14\/2019\/11\/16201315\/2020y04m16d_201306702.jpg\" width=\"80\" height=\"80\" style=\"\"  \/>\n            <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n        \n        \u52aa\u529b\u5024\u306e\u632f\u308a\u65b9\u3068\u30ea\u30bb\u30c3\u30c8\u65b9\u6cd5\uff5c\u304a\u3059\u3059\u3081\u306e\u7a3c\u304e\u5834\u6240      <\/div>\n      <div class=\"media-meta\">\n\n        \n                <small class=\"media-meta-date\">\n          2019\u5e7411\u670821\u65e5        <\/small>\n        \n                        <span class=\"label label-default label-post-type label-post-type-\u6295\u7a3f\">\u6295\u7a3f<\/span>\n                \n\n\n                                <span class=\"label label-default label-category label-category-\u80b2\u6210\u77e5\u8b58\">\u80b2\u6210\u77e5\u8b58<\/span>\n                                                        \n\n      <\/div>\n            <div class=\"media-desc\">\n        \u300e\u30dd\u30b1\u30c3\u30c8\u30e2\u30f3\u30b9\u30bf\u30fc \u30bd\u30fc\u30c9\u30fb\u30b7\u30fc\u30eb\u30c9(\u30dd\u30b1\u30e2\u30f3\u5263\u76fe)\u300f\u306e\u52aa\u529b\u5024\u306b\u3064\u3044\u3066\u7d39\u4ecb\u3057\u3066...      <\/div>\n      \n    <\/div>\n    <div class=\"clearfix\"><\/div>\n  <\/div>\n<\/a>\n\n  <\/div>\n<\/ul>\n\n<h2  class=\"\">\u95a2\u9023\u52d5\u753b<\/h2>\n","protected":false},"author":1,"featured_media":0,"menu_order":305,"comment_status":"open","ping_status":"closed","template":"","meta":{"event_start_date":[],"event_end_date":[],"external_thumbnail_url":"","redirect":"","last_comment_date":"","footnotes":"","name":"\u30d1\u30ef\u30fc\u30ea\u30b9\u30c8","effect":"\u6301\u305f\u305b\u308b\u3068\u300c\u3059\u3070\u3084\u3055\u300d\u304c\u534a\u5206\u306b\u306a\u308b\u304c\u3001\u300c\u3053\u3046\u3052\u304d\u300d\u306e\u304d\u305d\u30dd\u30a4\u30f3\u30c8\u304c\u3088\u304f\u4e0a\u304c\u308b","move":""},"item_type":"\u9053\u5177","class_list":["post-5844","item","type-item","status-publish","hentry","item_type-75"],"long_title":"\u3010\u30bd\u30fc\u30c9\u30b7\u30fc\u30eb\u30c9\u3011\u30d1\u30ef\u30fc\u30ea\u30b9\u30c8\u306e\u5165\u624b\u65b9\u6cd5\u3068\u52b9\u679c\u307e\u3068\u3081\u3010\u30dd\u30b1\u30e2\u30f3\u5263\u76fe\u3011","user":"hiro","str_count":0,"category_name":"","tag_name":"","is_pr":false,"pr_mode":null,"hide_ad":false,"noindex":null,"comment_count":0,"original_content":"","site_name":"\u30dd\u30b1\u30e2\u30f3 \u30bd\u30fc\u30c9\u30fb\u30b7\u30fc\u30eb\u30c9","is_valid_post_type":true,"is_password_required":false,"ogp_image_url":"https:\/\/tfi.gamepedia.jp\/image\/w=1200,h=630,fit=pad,f=webp\/media.gamepedia.jp\/gamepedia\/wp-content\/uploads\/2019\/12\/29124928\/no_img-480x267.png","thumbnail_url":"https:\/\/i0.wp.com\/s3-ap-northeast-1.amazonaws.com\/media.gamepedia\/gamepedia\/wp-content\/uploads\/2019\/12\/29124928\/no_img-480x267.png?resize=200%2C200&ssl=1","name":"\u30d1\u30ef\u30fc\u30ea\u30b9\u30c8","effect":"\u6301\u305f\u305b\u308b\u3068\u300c\u3059\u3070\u3084\u3055\u300d\u304c\u534a\u5206\u306b\u306a\u308b\u304c\u3001\u300c\u3053\u3046\u3052\u304d\u300d\u306e\u304d\u305d\u30dd\u30a4\u30f3\u30c8\u304c\u3088\u304f\u4e0a\u304c\u308b","move":"","_links":{"self":[{"href":"https:\/\/pokemon.gamepedia.jp\/ss\/wp-json\/wp\/v2\/items\/5844","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pokemon.gamepedia.jp\/ss\/wp-json\/wp\/v2\/items"}],"about":[{"href":"https:\/\/pokemon.gamepedia.jp\/ss\/wp-json\/wp\/v2\/types\/item"}],"author":[{"embeddable":true,"href":"https:\/\/pokemon.gamepedia.jp\/ss\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pokemon.gamepedia.jp\/ss\/wp-json\/wp\/v2\/comments?post=5844"}],"version-history":[{"count":1,"href":"https:\/\/pokemon.gamepedia.jp\/ss\/wp-json\/wp\/v2\/items\/5844\/revisions"}],"predecessor-version":[{"id":12159,"href":"https:\/\/pokemon.gamepedia.jp\/ss\/wp-json\/wp\/v2\/items\/5844\/revisions\/12159"}],"wp:attachment":[{"href":"https:\/\/pokemon.gamepedia.jp\/ss\/wp-json\/wp\/v2\/media?parent=5844"}],"wp:term":[{"taxonomy":"item_type","embeddable":true,"href":"https:\/\/pokemon.gamepedia.jp\/ss\/wp-json\/wp\/v2\/item_type?post=5844"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}